{"id":165,"count":4,"description":"","link":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/category\/disability-concerns\/","name":"Disability Concerns","slug":"disability-concerns","taxonomy":"category","parent":0,"meta":[],"meta_box":[],"_links":{"self":[{"href":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/wp-json\/wp\/v2\/categories\/165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/wp-json\/wp\/v2\/posts?categories=165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}