{"id":208,"count":2,"description":"","link":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/category\/dominican-republic\/","name":"Dominican Republic","slug":"dominican-republic","taxonomy":"category","parent":0,"meta":[],"meta_box":[],"_links":{"self":[{"href":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/wp-json\/wp\/v2\/categories\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dev.reliantcreative.org\/medical-ambasadors\/old-site\/wp-json\/wp\/v2\/posts?categories=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}